{"id":18693,"date":"2023-10-17T17:34:16","date_gmt":"2023-10-17T15:34:16","guid":{"rendered":"https:\/\/www.akuryprodukte.de\/?post_type=product&#038;p=18693"},"modified":"2023-10-17T17:38:12","modified_gmt":"2023-10-17T15:38:12","slug":"hnn-iii-nervus-oculomotorius","status":"publish","type":"product","link":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/","title":{"rendered":"HNN III Nervus oculomotorius"},"content":{"rendered":"<p><strong>III. HNN N.oculomotorius <\/strong><\/p>\n<p>Er enth\u00e4lt somatoefferente und viszeroefferente Fasern und steuert die meisten quergestreiften Muskeln des Auges an.<\/p>\n<p>Neben dem N.trochlearis und dem N.abducens\u00a0ist er daher ma\u00dfgeblich f\u00fcr die\u00a0<strong>Bewegungen des Auges<\/strong>\u00a0verantwortlich.<\/p>\n<p><strong>Der Chip dient dazu, den 3. Hirnnerv N.oculomotorius zu stabilisieren und mit allen seinen Funktionen zu unterst\u00fctzen.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>III. HNN N.oculomotorius Er enth\u00e4lt somatoefferente und viszeroefferente Fasern und steuert die meisten quergestreiften Muskeln des Auges an. Neben dem N.trochlearis und dem N.abducens\u00a0ist er daher ma\u00dfgeblich f\u00fcr die\u00a0Bewegungen des Auges\u00a0verantwortlich. Der Chip dient dazu, den 3. Hirnnerv N.oculomotorius zu stabilisieren und mit allen seinen Funktionen zu unterst\u00fctzen.<\/p>\n","protected":false},"featured_media":18695,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3003,34,490],"product_tag":[],"class_list":["post-18693","product","type-product","status-publish","has-post-thumbnail","product_cat-info-chips-gehirn","product_cat-info-chips-a-z","product_cat-info-chips-themenbereiche","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HNN III Nervus oculomotorius - akury<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HNN III Nervus oculomotorius - akury\" \/>\n<meta property=\"og:description\" content=\"III. HNN N.oculomotorius Er enth\u00e4lt somatoefferente und viszeroefferente Fasern und steuert die meisten quergestreiften Muskeln des Auges an. Neben dem N.trochlearis und dem N.abducens\u00a0ist er daher ma\u00dfgeblich f\u00fcr die\u00a0Bewegungen des Auges\u00a0verantwortlich. Der Chip dient dazu, den 3. Hirnnerv N.oculomotorius zu stabilisieren und mit allen seinen Funktionen zu unterst\u00fctzen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/\" \/>\n<meta property=\"og:site_name\" content=\"akury\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T15:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2023\/10\/HNN-III-neu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@heiko_wenner\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/\",\"name\":\"HNN III Nervus oculomotorius - akury\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/HNN-III-neu.png\",\"datePublished\":\"2023-10-17T15:34:16+00:00\",\"dateModified\":\"2023-10-17T15:38:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/HNN-III-neu.png\",\"contentUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/HNN-III-neu.png\",\"width\":575,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hnn-iii-nervus-oculomotorius\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HNN III Nervus oculomotorius\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\",\"name\":\"akury\",\"description\":\"Produkte f\u00fcr Ihr Wohlbefinden\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#organization\",\"name\":\"AkuRy GmbH\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo_AKY-p-512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo_AKY-p-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"AkuRy GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/bioenergetischesinformationsmanagement\\\/\",\"https:\\\/\\\/x.com\\\/heiko_wenner\",\"https:\\\/\\\/www.instagram.com\\\/akury_gmbh\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyItRPbJUon1m0Gq6kV2Izw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HNN III Nervus oculomotorius - akury","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/","og_locale":"en_US","og_type":"article","og_title":"HNN III Nervus oculomotorius - akury","og_description":"III. HNN N.oculomotorius Er enth\u00e4lt somatoefferente und viszeroefferente Fasern und steuert die meisten quergestreiften Muskeln des Auges an. Neben dem N.trochlearis und dem N.abducens\u00a0ist er daher ma\u00dfgeblich f\u00fcr die\u00a0Bewegungen des Auges\u00a0verantwortlich. Der Chip dient dazu, den 3. Hirnnerv N.oculomotorius zu stabilisieren und mit allen seinen Funktionen zu unterst\u00fctzen.","og_url":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/","og_site_name":"akury","article_publisher":"https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/","article_modified_time":"2023-10-17T15:38:12+00:00","og_image":[{"width":575,"height":575,"url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2023\/10\/HNN-III-neu.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@heiko_wenner","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/","url":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/","name":"HNN III Nervus oculomotorius - akury","isPartOf":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/#primaryimage"},"image":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/#primaryimage"},"thumbnailUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2023\/10\/HNN-III-neu.png","datePublished":"2023-10-17T15:34:16+00:00","dateModified":"2023-10-17T15:38:12+00:00","breadcrumb":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/#primaryimage","url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2023\/10\/HNN-III-neu.png","contentUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2023\/10\/HNN-III-neu.png","width":575,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hnn-iii-nervus-oculomotorius\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.akuryprodukte.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.akuryprodukte.de\/en\/shop-en\/"},{"@type":"ListItem","position":3,"name":"HNN III Nervus oculomotorius"}]},{"@type":"WebSite","@id":"https:\/\/www.akuryprodukte.de\/en\/#website","url":"https:\/\/www.akuryprodukte.de\/en\/","name":"akury","description":"Produkte f\u00fcr Ihr Wohlbefinden","publisher":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akuryprodukte.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.akuryprodukte.de\/en\/#organization","name":"AkuRy GmbH","url":"https:\/\/www.akuryprodukte.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.akuryprodukte.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2020\/09\/Logo_AKY-p-512.jpg","contentUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2020\/09\/Logo_AKY-p-512.jpg","width":512,"height":512,"caption":"AkuRy GmbH"},"image":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/","https:\/\/x.com\/heiko_wenner","https:\/\/www.instagram.com\/akury_gmbh\/","https:\/\/www.youtube.com\/channel\/UCyItRPbJUon1m0Gq6kV2Izw"]}]}},"_links":{"self":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product\/18693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/comments?post=18693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/media\/18695"}],"wp:attachment":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/media?parent=18693"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_brand?post=18693"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_cat?post=18693"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_tag?post=18693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}