{"id":21224,"date":"2025-01-31T10:19:56","date_gmt":"2025-01-31T09:19:56","guid":{"rendered":"https:\/\/www.akuryprodukte.de\/?post_type=product&#038;p=21224"},"modified":"2025-01-31T10:19:57","modified_gmt":"2025-01-31T09:19:57","slug":"hdn-2-arnika","status":"publish","type":"product","link":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/","title":{"rendered":"HDN 2 &#8211; Arnika"},"content":{"rendered":"<p><strong>HDN 2 Arnica<\/strong><\/p>\n<p>Arnica, auch bekannt als Bergwohlverleih oder Fallkraut, ist eine Heilpflanze, die in den europ\u00e4ischen Mittel- und Hochgebirgen w\u00e4chst.\u00a0<a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Sie geh\u00f6rt zur Familie der Korbbl\u00fctler und ist besonders f\u00fcr ihre entz\u00fcndungshemmenden, schmerzlindernden und durchblutungsf\u00f6rdernden Eigenschaften bekannt<\/a>.<\/p>\n<p>Wirkkraft von Arnica<\/p>\n<p>Die heilenden Eigenschaften von Arnica beruhen auf den in den Bl\u00fcten enthaltenen \u00e4therischen \u00d6len und Flavonoiden.\u00a0<a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Diese Inhaltsstoffe wirken entz\u00fcndungshemmend, blutdrucksenkend und f\u00f6rdern die Wundheilung<\/a>.\u00a0<a href=\"https:\/\/www.gesundfit.de\/heilkraeuter-heilpflanzen\/arnika-arnica-montana\/\">Ein wesentlicher Wirkstoff ist Helenalin, ein Sesquiterpenlacton, das f\u00fcr seine entz\u00fcndungshemmende Wirkung bekannt ist<\/a>.<\/p>\n<p>Anwendungsgebiete von Arnica<\/p>\n<p>Hier sind einige der h\u00e4ufigsten Anwendungsgebiete:<\/p>\n<ol>\n<li><a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Verletzungen und Prellungen: Arnica-Salben und -Gele werden oft bei Bluterg\u00fcssen, Prellungen und Verstauchungen eingesetzt, um Schwellungen und Schmerzen zu lindern<\/a>.<\/li>\n<li><a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Muskel- und Gelenkschmerzen: Bei rheumatischen Beschwerden und Muskelkater kann Arnica helfen, die Schmerzen zu reduzieren<\/a>.<\/li>\n<li><a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Wundheilung: Arnica f\u00f6rdert die Heilung von kleineren Wunden und Insektenstichen<\/a>.<\/li>\n<li><a href=\"https:\/\/www.netdoktor.de\/alternativmedizin\/homoeopathie\/arnica\/\">Entz\u00fcndungen im Mund- und Rachenraum: Als Gurgelmittel kann Arnica bei Entz\u00fcndungen im Mund- und Rachenraum helfen<\/a>.<\/li>\n<\/ol>\n<p>Der Chip enth\u00e4lt Frequenzen und Informationen von Arnica, die unterst\u00fctzend zur Linderung o.a. Symptome\/Anwendungsgebiete beitragen sollen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HDN 2 Arnica Arnica, auch bekannt als Bergwohlverleih oder Fallkraut, ist eine Heilpflanze, die in den europ\u00e4ischen Mittel- und Hochgebirgen w\u00e4chst.\u00a0Sie geh\u00f6rt zur Familie der Korbbl\u00fctler und ist besonders f\u00fcr ihre entz\u00fcndungshemmenden, schmerzlindernden und durchblutungsf\u00f6rdernden Eigenschaften bekannt. Wirkkraft von Arnica Die heilenden Eigenschaften von Arnica beruhen auf den in den Bl\u00fcten enthaltenen \u00e4therischen \u00d6len und [&hellip;]<\/p>\n","protected":false},"featured_media":21229,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3038],"product_tag":[],"class_list":["post-21224","product","type-product","status-publish","has-post-thumbnail","product_cat-heilung-aus-der-natur","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HDN 2 - Arnika - akury<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HDN 2 - Arnika - akury\" \/>\n<meta property=\"og:description\" content=\"HDN 2 Arnica Arnica, auch bekannt als Bergwohlverleih oder Fallkraut, ist eine Heilpflanze, die in den europ\u00e4ischen Mittel- und Hochgebirgen w\u00e4chst.\u00a0Sie geh\u00f6rt zur Familie der Korbbl\u00fctler und ist besonders f\u00fcr ihre entz\u00fcndungshemmenden, schmerzlindernden und durchblutungsf\u00f6rdernden Eigenschaften bekannt. Wirkkraft von Arnica Die heilenden Eigenschaften von Arnica beruhen auf den in den Bl\u00fcten enthaltenen \u00e4therischen \u00d6len und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/\" \/>\n<meta property=\"og:site_name\" content=\"akury\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T09:19:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2025\/01\/HDN-2-a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@heiko_wenner\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/\",\"name\":\"HDN 2 - Arnika - akury\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/HDN-2-a.png\",\"datePublished\":\"2025-01-31T09:19:56+00:00\",\"dateModified\":\"2025-01-31T09:19:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/HDN-2-a.png\",\"contentUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/HDN-2-a.png\",\"width\":575,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop\\\/hdn-2-arnika\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/shop-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HDN 2 &#8211; Arnika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\",\"name\":\"akury\",\"description\":\"Produkte f\u00fcr Ihr Wohlbefinden\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#organization\",\"name\":\"AkuRy GmbH\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo_AKY-p-512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.akuryprodukte.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Logo_AKY-p-512.jpg\",\"width\":512,\"height\":512,\"caption\":\"AkuRy GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.akuryprodukte.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/bioenergetischesinformationsmanagement\\\/\",\"https:\\\/\\\/x.com\\\/heiko_wenner\",\"https:\\\/\\\/www.instagram.com\\\/akury_gmbh\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyItRPbJUon1m0Gq6kV2Izw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HDN 2 - Arnika - akury","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/","og_locale":"en_US","og_type":"article","og_title":"HDN 2 - Arnika - akury","og_description":"HDN 2 Arnica Arnica, auch bekannt als Bergwohlverleih oder Fallkraut, ist eine Heilpflanze, die in den europ\u00e4ischen Mittel- und Hochgebirgen w\u00e4chst.\u00a0Sie geh\u00f6rt zur Familie der Korbbl\u00fctler und ist besonders f\u00fcr ihre entz\u00fcndungshemmenden, schmerzlindernden und durchblutungsf\u00f6rdernden Eigenschaften bekannt. Wirkkraft von Arnica Die heilenden Eigenschaften von Arnica beruhen auf den in den Bl\u00fcten enthaltenen \u00e4therischen \u00d6len und [&hellip;]","og_url":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/","og_site_name":"akury","article_publisher":"https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/","article_modified_time":"2025-01-31T09:19:57+00:00","og_image":[{"width":575,"height":575,"url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2025\/01\/HDN-2-a.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@heiko_wenner","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/","url":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/","name":"HDN 2 - Arnika - akury","isPartOf":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/#primaryimage"},"image":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/#primaryimage"},"thumbnailUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2025\/01\/HDN-2-a.png","datePublished":"2025-01-31T09:19:56+00:00","dateModified":"2025-01-31T09:19:57+00:00","breadcrumb":{"@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/#primaryimage","url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2025\/01\/HDN-2-a.png","contentUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2025\/01\/HDN-2-a.png","width":575,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/www.akuryprodukte.de\/en\/shop\/hdn-2-arnika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.akuryprodukte.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.akuryprodukte.de\/en\/shop-en\/"},{"@type":"ListItem","position":3,"name":"HDN 2 &#8211; Arnika"}]},{"@type":"WebSite","@id":"https:\/\/www.akuryprodukte.de\/en\/#website","url":"https:\/\/www.akuryprodukte.de\/en\/","name":"akury","description":"Produkte f\u00fcr Ihr Wohlbefinden","publisher":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akuryprodukte.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.akuryprodukte.de\/en\/#organization","name":"AkuRy GmbH","url":"https:\/\/www.akuryprodukte.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.akuryprodukte.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2020\/09\/Logo_AKY-p-512.jpg","contentUrl":"https:\/\/www.akuryprodukte.de\/wp-content\/uploads\/2020\/09\/Logo_AKY-p-512.jpg","width":512,"height":512,"caption":"AkuRy GmbH"},"image":{"@id":"https:\/\/www.akuryprodukte.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/bioenergetischesinformationsmanagement\/","https:\/\/x.com\/heiko_wenner","https:\/\/www.instagram.com\/akury_gmbh\/","https:\/\/www.youtube.com\/channel\/UCyItRPbJUon1m0Gq6kV2Izw"]}]}},"_links":{"self":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product\/21224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/comments?post=21224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/media\/21229"}],"wp:attachment":[{"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/media?parent=21224"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_brand?post=21224"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_cat?post=21224"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.akuryprodukte.de\/en\/wp-json\/wp\/v2\/product_tag?post=21224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}